{"id":16423,"date":"2026-07-02T09:38:48","date_gmt":"2026-07-02T07:38:48","guid":{"rendered":"https:\/\/adiznctb3b.wpdns.site\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/"},"modified":"2026-07-02T09:38:48","modified_gmt":"2026-07-02T07:38:48","slug":"elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech","status":"publish","type":"post","link":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/","title":{"rendered":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech"},"content":{"rendered":"<h4>Na\u0161e elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar se ji\u017e osv\u011bd\u010dily: ji\u017e dnes jezd\u00ed ve m\u011bstech jako Stockholm, Kol\u00edn nad R\u00fdnem, Kapfenberg nebo Koper \u2013 spolehliv\u011b, bezbari\u00e9rov\u011b a bez emis\u00ed.<\/h4>\n<p>V roce 2017 jsme s modelem E-Solar City vyvinuli novou t\u0159\u00eddu elektrick\u00fdch autobus\u016f \u2013 kompaktn\u00edch, bezbari\u00e9rov\u00fdch a s dojezdem a\u017e 160 kilometr\u016f. V roce 2018 za\u010daly prvn\u00ed dod\u00e1vky a mezit\u00edm se tato vozidla stala b\u011b\u017enou sou\u010d\u00e1st\u00ed evropsk\u00e9ho ka\u017edodenn\u00edho \u017eivota. <\/p>\n<p>A\u0165 u\u017e v m\u011bstsk\u00e9 doprav\u011b, jako ob\u010dansk\u00fd autobus nebo v men\u0161\u00edch obc\u00edch \u2013 model E-Solar City dokazuje, \u017ee elektromobilita funguje i ve t\u0159\u00edd\u00e1ch kompaktn\u00edch vozidel. Obzvl\u00e1\u0161t\u011b oce\u0148ovan\u00e1 je kombinace snadn\u00e9ho ovl\u00e1d\u00e1n\u00ed (\u0159idi\u010dsk\u00fd pr\u016fkaz skupiny B) a prakti\u010dnosti pro ka\u017edodenn\u00ed pou\u017eit\u00ed. <\/p>\n<p>Jsme r\u00e1di, \u017ee spole\u010dnosti jako Bergvarabus, Postbus a MVG vyu\u017e\u00edvaj\u00ed na\u0161e autobusy \u2013 a d\u00e1vaj\u00ed tak jasn\u00fd sign\u00e1l ve prosp\u011bch udr\u017eiteln\u00e9 mobility.<\/p>\n<p>\u2192 V\u00edce o na\u0161ich m\u011bstsk\u00fdch autobusech<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na\u0161e elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar se ji\u017e osv\u011bd\u010dily: ji\u017e dnes jezd\u00ed ve m\u011bstech jako Stockholm, Kol\u00edn nad R\u00fdnem, Kapfenberg nebo<\/p>\n","protected":false},"author":3,"featured_media":16424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[247],"tags":[],"class_list":["post-16423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bez-kategorie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus\" \/>\n<meta property=\"og:description\" content=\"Na\u0161e elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar se ji\u017e osv\u011bd\u010dily: ji\u017e dnes jezd\u00ed ve m\u011bstech jako Stockholm, Kol\u00edn nad R\u00fdnem, Kapfenberg nebo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/\" \/>\n<meta property=\"og:site_name\" content=\"K-Bus\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-02T07:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Pirecki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Pirecki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/\"},\"author\":{\"name\":\"Andrea Pirecki\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/#\\\/schema\\\/person\\\/b79a4f67da3db34c482fb3becd6e4245\"},\"headline\":\"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech\",\"datePublished\":\"2026-07-02T07:38:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/\"},\"wordCount\":189,\"image\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/k-bus.at\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e-daily5_solar_xl_kbus-e1781161208356.jpg\",\"articleSection\":[\"Bez kategorie\"],\"inLanguage\":\"cs\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/\",\"url\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/\",\"name\":\"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/k-bus.at\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e-daily5_solar_xl_kbus-e1781161208356.jpg\",\"datePublished\":\"2026-07-02T07:38:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/#\\\/schema\\\/person\\\/b79a4f67da3db34c482fb3becd6e4245\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/k-bus.at\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e-daily5_solar_xl_kbus-e1781161208356.jpg\",\"contentUrl\":\"https:\\\/\\\/k-bus.at\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e-daily5_solar_xl_kbus-e1781161208356.jpg\",\"width\":1000,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/k-bus-s-r-o\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/\",\"name\":\"K-Bus\",\"description\":\"Smart Mobility\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/cs\\\/#\\\/schema\\\/person\\\/b79a4f67da3db34c482fb3becd6e4245\",\"name\":\"Andrea Pirecki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g\",\"caption\":\"Andrea Pirecki\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/","og_locale":"cs_CZ","og_type":"article","og_title":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus","og_description":"Na\u0161e elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar se ji\u017e osv\u011bd\u010dily: ji\u017e dnes jezd\u00ed ve m\u011bstech jako Stockholm, Kol\u00edn nad R\u00fdnem, Kapfenberg nebo","og_url":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/","og_site_name":"K-Bus","article_published_time":"2026-07-02T07:38:48+00:00","og_image":[{"width":1000,"height":715,"url":"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg","type":"image\/jpeg"}],"author":"Andrea Pirecki","twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Andrea Pirecki","Odhadovan\u00e1 doba \u010dten\u00ed":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#article","isPartOf":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/"},"author":{"name":"Andrea Pirecki","@id":"https:\/\/k-bus.at\/cs\/#\/schema\/person\/b79a4f67da3db34c482fb3becd6e4245"},"headline":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech","datePublished":"2026-07-02T07:38:48+00:00","mainEntityOfPage":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/"},"wordCount":189,"image":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#primaryimage"},"thumbnailUrl":"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg","articleSection":["Bez kategorie"],"inLanguage":"cs"},{"@type":"WebPage","@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/","url":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/","name":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech - K-Bus","isPartOf":{"@id":"https:\/\/k-bus.at\/cs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#primaryimage"},"image":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#primaryimage"},"thumbnailUrl":"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg","datePublished":"2026-07-02T07:38:48+00:00","author":{"@id":"https:\/\/k-bus.at\/cs\/#\/schema\/person\/b79a4f67da3db34c482fb3becd6e4245"},"breadcrumb":{"@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#primaryimage","url":"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg","contentUrl":"https:\/\/k-bus.at\/wp-content\/uploads\/2026\/01\/e-daily5_solar_xl_kbus-e1781161208356.jpg","width":1000,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/k-bus.at\/cs\/elektricke-mestske-autobusy-e-solar-uspesne-jezdi-v-evropskych-mestech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-bus.at\/cs\/k-bus-s-r-o\/"},{"@type":"ListItem","position":2,"name":"Elektrick\u00e9 m\u011bstsk\u00e9 autobusy E-Solar \u00fasp\u011b\u0161n\u011b jezd\u00ed v evropsk\u00fdch m\u011bstech"}]},{"@type":"WebSite","@id":"https:\/\/k-bus.at\/cs\/#website","url":"https:\/\/k-bus.at\/cs\/","name":"K-Bus","description":"Smart Mobility","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-bus.at\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Person","@id":"https:\/\/k-bus.at\/cs\/#\/schema\/person\/b79a4f67da3db34c482fb3becd6e4245","name":"Andrea Pirecki","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/secure.gravatar.com\/avatar\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e7490fdafa64acbdd60eca8c45c7de318b19f18b275b5c3183eff64bd4dd9e8?s=96&d=mm&r=g","caption":"Andrea Pirecki"}}]}},"_links":{"self":[{"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/posts\/16423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/comments?post=16423"}],"version-history":[{"count":0,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/posts\/16423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/media\/16424"}],"wp:attachment":[{"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/media?parent=16423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/categories?post=16423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-bus.at\/cs\/wp-json\/wp\/v2\/tags?post=16423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}