{"id":16279,"date":"2026-07-02T09:17:42","date_gmt":"2026-07-02T07:17:42","guid":{"rendered":"https:\/\/adiznctb3b.wpdns.site\/aviso-legal\/"},"modified":"2026-07-02T09:17:49","modified_gmt":"2026-07-02T07:17:49","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/k-bus.at\/es\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16279\" class=\"elementor elementor-16279 elementor-10\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-60fc9095 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60fc9095\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-441c5ef4\" data-id=\"441c5ef4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49bdad34 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"49bdad34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>K-BUS GmbH<\/strong><br\/>Industriegasse I\/1<br\/>7053 Hornstein<br\/>Austria<\/p><p>Tel.: <a href=\"tel:+430268922160\">+43 2689 2216 12<\/a><br\/>Fax: +43 2689 2216 40<br\/><a href=\"mailto:office@k-bus.at\">office@k-bus.at<\/a><\/p><p>Fabricaci\u00f3n y comercializaci\u00f3n de autobuses<\/p><p>N.\u00ba de identificaci\u00f3n fiscal ATU75633138<\/p><p>FN 534370p<br\/>Tribunal Regional de Eisenstadt<\/p><p>Miembro de la C\u00e1mara de Comercio de Burgenland, sector del comercio de veh\u00edculos<br\/>Miembro de la C\u00e1mara de Comercio de Burgenland, sector del transporte en turismos<\/p><p>Ayuntamiento de la capital regional de Freistadt Eisenstadt<br\/>Derecho profesional: <a href=\"https:\/\/www.ris.bka.gv.at\/GeltendeFassung.wxe?Abfrage=Bundesnormen&#038;Gesetzesnummer=10007517\">Reglamento de actividades econ\u00f3micas<\/a><\/p><p>Concepci\u00f3n, dise\u00f1o y desarrollo de la p\u00e1gina web: <a href=\"https:\/\/giefing.net\/\">Giefing web | media<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>K-BUS GmbHIndustriegasse I\/17053 HornsteinAustria Tel.: +43 2689 2216 12Fax: +43 2689 2216 40office@k-bus.at Fabricaci\u00f3n y comercializaci\u00f3n de autobuses N.\u00ba de<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16279","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal - K-Bus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-bus.at\/es\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - K-Bus\" \/>\n<meta property=\"og:description\" content=\"K-BUS GmbHIndustriegasse I\/17053 HornsteinAustria Tel.: +43 2689 2216 12Fax: +43 2689 2216 40office@k-bus.at Fabricaci\u00f3n y comercializaci\u00f3n de autobuses N.\u00ba de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-bus.at\/es\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"K-Bus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T07:17:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/es\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/k-bus.at\\\/es\\\/aviso-legal\\\/\",\"name\":\"Aviso legal - K-Bus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/es\\\/#website\"},\"datePublished\":\"2026-07-02T07:17:42+00:00\",\"dateModified\":\"2026-07-02T07:17:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/es\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-bus.at\\\/es\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/es\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-bus.at\\\/es\\\/k-bus-gmbh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/k-bus.at\\\/es\\\/\",\"name\":\"K-Bus\",\"description\":\"Smart Mobility\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-bus.at\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - K-Bus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-bus.at\/es\/aviso-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Aviso legal - K-Bus","og_description":"K-BUS GmbHIndustriegasse I\/17053 HornsteinAustria Tel.: +43 2689 2216 12Fax: +43 2689 2216 40office@k-bus.at Fabricaci\u00f3n y comercializaci\u00f3n de autobuses N.\u00ba de","og_url":"https:\/\/k-bus.at\/es\/aviso-legal\/","og_site_name":"K-Bus","article_modified_time":"2026-07-02T07:17:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-bus.at\/es\/aviso-legal\/","url":"https:\/\/k-bus.at\/es\/aviso-legal\/","name":"Aviso legal - K-Bus","isPartOf":{"@id":"https:\/\/k-bus.at\/es\/#website"},"datePublished":"2026-07-02T07:17:42+00:00","dateModified":"2026-07-02T07:17:49+00:00","breadcrumb":{"@id":"https:\/\/k-bus.at\/es\/aviso-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-bus.at\/es\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-bus.at\/es\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-bus.at\/es\/k-bus-gmbh\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/k-bus.at\/es\/#website","url":"https:\/\/k-bus.at\/es\/","name":"K-Bus","description":"Smart Mobility","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-bus.at\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/pages\/16279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/comments?post=16279"}],"version-history":[{"count":0,"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/pages\/16279\/revisions"}],"wp:attachment":[{"href":"https:\/\/k-bus.at\/es\/wp-json\/wp\/v2\/media?parent=16279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}