{"id":16235,"date":"2026-07-02T09:16:53","date_gmt":"2026-07-02T07:16:53","guid":{"rendered":"https:\/\/adiznctb3b.wpdns.site\/protezione-dei-dati\/"},"modified":"2026-07-02T09:16:59","modified_gmt":"2026-07-02T07:16:59","slug":"protezione-dei-dati","status":"publish","type":"page","link":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/","title":{"rendered":"Protezione dei dati"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16235\" class=\"elementor elementor-16235 elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-5d10340d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d10340d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38f2258a\" data-id=\"38f2258a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33e7b156 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"33e7b156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 id=\"heading_Erklaerung_zur_Informationspflicht_2\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 32; line-height: 1.5;\" data-fontsize=\"32\" data-lineheight=\"48px\">Dichiarazione relativa all&#8217;obbligo di informazione<\/h3><h4 id=\"heading__Datenschutzerklaerung_\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">Informativa sulla privacy<\/h4><p>La tutela dei Suoi dati personali \u00e8 per noi una priorit\u00e0 assoluta. Trattiamo quindi i Suoi dati esclusivamente in conformit\u00e0 alle disposizioni di legge (DSG, TKG 2003, GDPR). Nella presente informativa sulla privacy Le forniamo informazioni sugli aspetti pi\u00f9 importanti del trattamento dei dati nell\u2019ambito del nostro sito web.  <\/p><h4 id=\"heading_Kontakt_mit_uns\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">Contattaci<\/h4><p>Se ci contattate via e-mail, i dati da voi forniti saranno conservati presso di noi per sei mesi al fine di gestire la richiesta e in caso di ulteriori domande. Non trasmetteremo tali dati a terzi senza il vostro consenso. <\/p><h4 id=\"heading_Cookies\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">Cookie<\/h4><p>Il nostro sito web utilizza i cosiddetti cookie. Si tratta di piccoli file di testo che vengono memorizzati sul vostro dispositivo tramite il browser. Non causano alcun danno.  <\/p><p>Utilizziamo i cookie per rendere il nostro sito pi\u00f9 intuitivo. Alcuni cookie rimangono memorizzati sul Suo dispositivo fino a quando non li cancella. Ci consentono di riconoscere il Suo browser alla Sua prossima visita.  <\/p><p>Se non lo desiderate, potete configurare il vostro browser in modo che vi avvisi quando vengono impostati dei cookie e che vi consenta di accettarli solo in casi specifici.<\/p><p>Se si disattivano i cookie, la funzionalit\u00e0 del nostro sito web potrebbe risultare limitata.<\/p><h4 class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">Pixel di Facebook<\/h4><p>Il nostro sito web utilizza la funzione di remarketing \u201cFacebook Pixel\u201d di Facebook Inc. (\u201cFacebook\u201d). Questa funzione serve a mostrare ai visitatori di questo sito web <a href=\"https:\/\/www.trafficmaxx.de\/social-media-marketing\">annunci pubblicitari personalizzati in base ai loro interessi (\u201cFacebook Ads\u201d) quando visitano il social network Facebook<\/a>. A tal fine, sul nostro sito web \u00e8 stato implementato il Facebook Pixel. Tramite il Facebook Pixel, quando si visita il sito web viene stabilito un collegamento diretto con i server di Facebook. In questo modo viene comunicato al server di Facebook che avete visitato questo sito web e Facebook associa questa informazione al vostro account utente personale di Facebook.     <\/p><p>Per ulteriori informazioni sulla raccolta e l&#8217;utilizzo dei dati da parte di Facebook, nonch\u00e9 sui diritti dell&#8217;utente in materia e sulle possibilit\u00e0 di tutelare la propria privacy, consultare l&#8217;informativa sulla privacy di Facebook all&#8217;indirizzo <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\">https:\/\/www.facebook.com\/about\/privacy\/<\/a>.<\/p><p>In alternativa, \u00e8 possibile disattivare la funzione di remarketing di Facebook all&#8217;indirizzo <a href=\"https:\/\/www.facebook.com\/settings\/?tab=ads#_=_\">https:\/\/www.facebook.com\/settings\/?tab=ads#_=_<\/a>. Per farlo, \u00e8 necessario aver effettuato l&#8217;accesso a Facebook. <\/p><h4 id=\"heading_Ihre_Rechte\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">I vostri diritti<\/h4><p>In linea di principio, Lei ha diritto all\u2019accesso, alla rettifica, alla cancellazione, alla limitazione del trattamento, alla portabilit\u00e0 dei dati, al ritiro del consenso e all\u2019opposizione. Se ritiene che il trattamento dei Suoi dati violi la normativa sulla protezione dei dati o che i Suoi diritti in materia siano stati altrimenti lesi, pu\u00f2 presentare un reclamo all\u2019autorit\u00e0 di controllo. In Austria, tale autorit\u00e0 \u00e8 l\u2019Autorit\u00e0 per la protezione dei dati.  <\/p><h4 id=\"heading_Sie_erreichen_uns_unter_folgenden_Kontaktdaten_\" class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 28; line-height: 1.5;\" data-fontsize=\"28\" data-lineheight=\"42px\">Potete contattarci ai seguenti recapiti:<\/h4><p>K-Bus GmbH<br\/>Industriegasse I\/1<br\/>7053 Hornstein, Austria<br\/>Tel.: <a href=\"tel:\/\/00432689221612\">+43 2689 2216 12<\/a><br\/>E-mail: <a href=\"mailto:office@k-bus.at\">office@k-bus.at<\/a><br\/>Sito web: www.k-bus.at<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dichiarazione relativa all&#8217;obbligo di informazione Informativa sulla privacy La tutela dei Suoi dati personali \u00e8 per noi una priorit\u00e0 assoluta.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16235","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protezione dei dati - K-Bus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-bus.at\/it\/protezione-dei-dati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protezione dei dati - K-Bus\" \/>\n<meta property=\"og:description\" content=\"Dichiarazione relativa all&#8217;obbligo di informazione Informativa sulla privacy La tutela dei Suoi dati personali \u00e8 per noi una priorit\u00e0 assoluta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-bus.at\/it\/protezione-dei-dati\/\" \/>\n<meta property=\"og:site_name\" content=\"K-Bus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T07:16:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/protezione-dei-dati\\\/\",\"url\":\"https:\\\/\\\/k-bus.at\\\/it\\\/protezione-dei-dati\\\/\",\"name\":\"Protezione dei dati - K-Bus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/#website\"},\"datePublished\":\"2026-07-02T07:16:53+00:00\",\"dateModified\":\"2026-07-02T07:16:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/protezione-dei-dati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-bus.at\\\/it\\\/protezione-dei-dati\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/protezione-dei-dati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-bus.at\\\/it\\\/k-bus-gmbh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protezione dei dati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/k-bus.at\\\/it\\\/\",\"name\":\"K-Bus\",\"description\":\"Smart Mobility\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-bus.at\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protezione dei dati - K-Bus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/","og_locale":"it_IT","og_type":"article","og_title":"Protezione dei dati - K-Bus","og_description":"Dichiarazione relativa all&#8217;obbligo di informazione Informativa sulla privacy La tutela dei Suoi dati personali \u00e8 per noi una priorit\u00e0 assoluta.","og_url":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/","og_site_name":"K-Bus","article_modified_time":"2026-07-02T07:16:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/","url":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/","name":"Protezione dei dati - K-Bus","isPartOf":{"@id":"https:\/\/k-bus.at\/it\/#website"},"datePublished":"2026-07-02T07:16:53+00:00","dateModified":"2026-07-02T07:16:59+00:00","breadcrumb":{"@id":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-bus.at\/it\/protezione-dei-dati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-bus.at\/it\/protezione-dei-dati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-bus.at\/it\/k-bus-gmbh\/"},{"@type":"ListItem","position":2,"name":"Protezione dei dati"}]},{"@type":"WebSite","@id":"https:\/\/k-bus.at\/it\/#website","url":"https:\/\/k-bus.at\/it\/","name":"K-Bus","description":"Smart Mobility","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-bus.at\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/pages\/16235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/comments?post=16235"}],"version-history":[{"count":0,"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/pages\/16235\/revisions"}],"wp:attachment":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/media?parent=16235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}