{"id":291,"count":2,"description":"\n\n\n\n\n\n\n<strong>Autobus per cittadini e comunit\u00e0<\/strong>\nI nostri autobus civici e comunali sono veicoli compatti e privi di barriere architettoniche, destinati all\u2019uso locale presso comuni, associazioni e strutture sociali. Sono economici da gestire, possono essere equipaggiati in modo flessibile e sono perfettamente adattati alle esigenze locali. \nGrazie alla patente di categoria B, possono essere guidati anche da volontari qualificati o da collaboratori. Sono quindi ideali per servizi di trasporto per i cittadini, collegamenti pendolari o piccoli servizi di trasporto di linea. \nGrazie a una tecnologia di base collaudata, a un design degli interni privo di barriere architettoniche con pianale ribassato e a motorizzazioni alternative opzionali, questi veicoli sono affidabili, durevoli e perfettamente adatti all\u2019uso quotidiano.\n\n\n\n\n\n\n\n\n\n","link":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/","name":"Autobus per cittadini e comunit\u00e0","slug":"autobus-per-cittadini-e-comunita","taxonomy":"typ","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autobus per cittadini e comunit\u00e0 Archivi - K-Bus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autobus per cittadini e comunit\u00e0 Archivi - K-Bus\" \/>\n<meta property=\"og:description\" content=\"Autobus per cittadini e comunit\u00e0 I nostri autobus civici e comunali sono veicoli compatti e privi di barriere architettoniche, destinati all\u2019uso locale presso comuni, associazioni e strutture sociali. Sono economici da gestire, possono essere equipaggiati in modo flessibile e sono perfettamente adattati alle esigenze locali. Grazie alla patente di categoria B, possono essere guidati anche da volontari qualificati o da collaboratori. Sono quindi ideali per servizi di trasporto per i cittadini, collegamenti pendolari o piccoli servizi di trasporto di linea. Grazie a una tecnologia di base collaudata, a un design degli interni privo di barriere architettoniche con pianale ribassato e a motorizzazioni alternative opzionali, questi veicoli sono affidabili, durevoli e perfettamente adatti all\u2019uso quotidiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/\" \/>\n<meta property=\"og:site_name\" content=\"K-Bus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/typ\\\/autobus-per-cittadini-e-comunita\\\/\",\"url\":\"https:\\\/\\\/k-bus.at\\\/it\\\/typ\\\/autobus-per-cittadini-e-comunita\\\/\",\"name\":\"Autobus per cittadini e comunit\u00e0 Archivi - K-Bus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/typ\\\/autobus-per-cittadini-e-comunita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/typ\\\/autobus-per-cittadini-e-comunita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-bus.at\\\/it\\\/k-bus-gmbh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autobus per cittadini e comunit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-bus.at\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/k-bus.at\\\/it\\\/\",\"name\":\"K-Bus\",\"description\":\"Smart Mobility\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-bus.at\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autobus per cittadini e comunit\u00e0 Archivi - K-Bus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/","og_locale":"it_IT","og_type":"article","og_title":"Autobus per cittadini e comunit\u00e0 Archivi - K-Bus","og_description":"Autobus per cittadini e comunit\u00e0 I nostri autobus civici e comunali sono veicoli compatti e privi di barriere architettoniche, destinati all\u2019uso locale presso comuni, associazioni e strutture sociali. Sono economici da gestire, possono essere equipaggiati in modo flessibile e sono perfettamente adattati alle esigenze locali. Grazie alla patente di categoria B, possono essere guidati anche da volontari qualificati o da collaboratori. Sono quindi ideali per servizi di trasporto per i cittadini, collegamenti pendolari o piccoli servizi di trasporto di linea. Grazie a una tecnologia di base collaudata, a un design degli interni privo di barriere architettoniche con pianale ribassato e a motorizzazioni alternative opzionali, questi veicoli sono affidabili, durevoli e perfettamente adatti all\u2019uso quotidiano.","og_url":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/","og_site_name":"K-Bus","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/","url":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/","name":"Autobus per cittadini e comunit\u00e0 Archivi - K-Bus","isPartOf":{"@id":"https:\/\/k-bus.at\/it\/#website"},"breadcrumb":{"@id":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/k-bus.at\/it\/typ\/autobus-per-cittadini-e-comunita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-bus.at\/it\/k-bus-gmbh\/"},{"@type":"ListItem","position":2,"name":"Autobus per cittadini e comunit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/k-bus.at\/it\/#website","url":"https:\/\/k-bus.at\/it\/","name":"K-Bus","description":"Smart Mobility","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-bus.at\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/typ\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/typ"}],"about":[{"href":"https:\/\/k-bus.at\/it\/wp-json\/wp\/v2\/taxonomies\/typ"}]}}